{"id":10286,"date":"2018-12-24T15:27:08","date_gmt":"2018-12-24T15:27:08","guid":{"rendered":"https:\/\/thuiszorgeuroclinicarincon.com\/?page_id=10286"},"modified":"2018-12-27T09:58:46","modified_gmt":"2018-12-27T09:58:46","slug":"aviso-legal","status":"publish","type":"page","link":"https:\/\/thuiszorgeuroclinicarincon.com\/nl\/aviso-legal\/","title":{"rendered":"Aviso legal"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Este portal, cuyo titular es DIAGNOSTICS UNITS SPAIN, S.L. &#8211; HOME CARE EUROCL\u00cdNICA RINC\u00d3N, est\u00e1 constituido por los sitios web asociados a los dominios https:\/\/www.thuiszorgeuroclinicarincon.com<\/p>\n<h2>Propiedad intelectual e industrial<\/h2>\n<p>El dise\u00f1o de esta web y sus c\u00f3digos fuente, as\u00ed como los logos, marcas y dem\u00e1s signos distintivos que aparecen en el mismo pertenecen a DIAGNOSTICS UNITS SPAIN, S.L. &#8211; HOME CARE EUROCL\u00cdNICA RINC\u00d3N y est\u00e1n protegidos por los correspondientes derechos de propiedad intelectual e industrial. La utilizaci\u00f3n no autorizada de la informaci\u00f3n contenida en este Sitio, as\u00ed como los perjuicios ocasionados en los derechos de propiedad intelectual e industrial de DIAGNOSTICS UNITS SPAIN, S.L. &#8211; HOME CARE EUROCL\u00cdNICA RINC\u00d3N, pueden dar lugar al ejercicio de las acciones que legalmente correspondan y, si procede, a las responsabilidades que de dicho ejercicio se deriven.<\/p>\n<h2>Responsabilidad de los contenidos<\/h2>\n<p>DIAGNOSTICS UNITS SPAIN, S.L. &#8211; HOME CARE EUROCL\u00cdNICA RINC\u00d3N no se hace responsable de la legalidad de otros sitios web de terceros desde los que pueda accederse a la web. DIAGNOSTICS UNITS SPAIN, S.L. &#8211; EUROCL\u00cdNICA RINC\u00d3N tampoco responde por la legalidad de otros sitios web de terceros, que pudieran estar vinculados o enlazados desde esta web.<\/p>\n<p>DIAGNOSTICS UNITS SPAIN, S.L. &#8211; HOME CARE EUROCL\u00cdNICA RINC\u00d3N se reserva el derecho a realizar cambios en el sitio web sin previo aviso, al objeto de mantener actualizada su informaci\u00f3n, a\u00f1adiendo, modificando, corrigiendo o eliminando los contenidos publicados o el dise\u00f1o de la web.<\/p>\n<p>DIAGNOSTICS UNITS SPAIN, S.L. &#8211; HOME CARE EUROCL\u00cdNICA RINC\u00d3N no ser\u00e1 responsable del uso que terceros hagan de la informaci\u00f3n publicada en la web, ni tampoco de los da\u00f1os sufridos o p\u00e9rdidas econ\u00f3micas que, de forma directa o indirecta, produzcan o puedan producir perjuicios econ\u00f3micos, materiales o sobre datos, provocados por el uso de dicha informaci\u00f3n.<\/p>\n<h2>Condiciones de uso del portal para los usuarios<\/h2>\n<p>Queda expresamente prohibido el uso de esta web con fines lesivos sobre bienes o intereses de DIAGNOSTICS UNITS SPAIN, S.L. &#8211; HOME CARE EUROCL\u00cdNICA RINC\u00d3N o de terceros o que de cualquier otra forma sobrecarguen, da\u00f1en o inutilicen las redes, servidores y dem\u00e1s equipos inform\u00e1ticos DIAGNOSTICS UNITS SPAIN, S.L. &#8211; HOME CARE EUROCL\u00cdNICA RINC\u00d3N, o de terceros.<\/p>\n<p>En el caso de que el Usuario tuviera conocimiento de que sitios enlazados remitan a p\u00e1ginas cuyos contenidos o servicios son il\u00edcitos, nocivos, denigrantes, violentos o contrarios a la moral le agradecer\u00edamos nos lo comunicara de forma inmediata.<\/p>\n<h2>Redes sociales<\/h2>\n<p>Al hacerte fan, seguidor o an\u00e1logos de nuestra empresa en la vertiente de las distintas redes sociales, en el contexto de este tratamiento debes tener en cuenta que DIAGNOSTICS UNITS SPAIN, S.L. &#8211; HOME CARE EUROCL\u00cdNICA RINC\u00d3N \u00fanicamente puede consultar o dar de baja tus datos de forma restringida al tener un perfil espec\u00edfico. Cualquier rectificaci\u00f3n de tus datos o restricci\u00f3n de informaci\u00f3n o de publicaciones debes realizarla a trav\u00e9s de la configuraci\u00f3n de tu perfil o usuario en la propia red social. Por defecto consientes:<\/p>\n<ol class=\"letter\">\n<li>El tratamiento de tus datos personales en el entorno de dicha red social y conforme a sus pol\u00edticas de Privacidad:\n<ul>\n<li>Facebook http:\/\/www.facebook.com\/policy.php?ref=pf<\/li>\n<li>Twitter http:\/\/twitter.com\/privacy<\/li>\n<li>Tuenti http:\/\/corporate.tuenti.com\/es\/privacy<\/li>\n<\/ul>\n<\/li>\n<li>el acceso de DIAGNOSTICS UNITS SPAIN, S.L. &#8211; HOME CARE EUROCL\u00cdNICA RINC\u00d3N a los datos contenidos en tu perfil o biograf\u00eda, dependiendo\u00a0de la configuraci\u00f3n que tengas de tu privacidad en cada red, estos ser\u00e1n m\u00e1s o menos amplios.<\/li>\n<li>A que las noticias publicadas sobre nuestros eventos, o nuestros comentarios pueda aparecer en tu muro o biograf\u00eda.<\/li>\n<li>A que las noticias publicadas sobre nuestros eventos, o nuestros comentarios pueda aparecer en tu muro o biograf\u00eda.<\/li>\n<\/ol>\n<p>Si quieres dejar de seguirnos, s\u00f3lo tienes que pinchar la opci\u00f3n &#8220;Dejar de ser fan&#8221; o \u201cdejar de seguir\u201d. Puedes ejercer los derechos de acceso, rectificaci\u00f3n, cancelaci\u00f3n y oposici\u00f3n en cualquier momento, mediante escrito, dirigido a la direcci\u00f3n que aparece arriba o enviando un e-mail a DIAGNOSTICS UNITS SPAIN, S.L. &#8211; HOME CARE EUROCL\u00cdNICA RINC\u00d3N<\/p>\n<h2>Ley aplicable<\/h2>\n<p>La ley aplicable en caso de disputa o conflicto de interpretaci\u00f3n de los t\u00e9rminos que conforman este aviso legal, as\u00ed como cualquier cuesti\u00f3n relacionada con los servicios del presente portal, ser\u00e1 la ley espa\u00f1ola.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Este portal, cuyo titular es DIAGNOSTICS UNITS SPAIN, S.L. &#8211; HOME CARE EUROCL\u00cdNICA RINC\u00d3N, est\u00e1 constituido por los sitios web asociados a los dominios https:\/\/www.thuiszorgeuroclinicarincon.com<\/p>\n<h2>Propiedad intelectual e industrial<\/h2>\n<p>El dise\u00f1o de esta web y sus c\u00f3digos fuente, as\u00ed como los logos, marcas y dem\u00e1s signos distintivos que aparecen en el mismo pertenecen a DIAGNOSTICS UNITS SPAIN,<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.2.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aviso legal - Thuiszorg Euro Cl\u00ednica Rinc\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thuiszorgeuroclinicarincon.com\/nl\/aviso-legal\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aviso legal - Thuiszorg Euro Cl\u00ednica Rinc\u00f3n\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text]Este portal, cuyo titular es DIAGNOSTICS UNITS SPAIN, S.L. &#8211; HOME CARE EUROCL\u00cdNICA RINC\u00d3N, est\u00e1 constituido por los sitios web asociados a los dominios https:\/\/www.thuiszorgeuroclinicarincon.com Propiedad intelectual e industrial El dise\u00f1o de esta web y sus c\u00f3digos fuente, as\u00ed como los logos, marcas y dem\u00e1s signos distintivos que aparecen en el mismo pertenecen a DIAGNOSTICS UNITS SPAIN,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thuiszorgeuroclinicarincon.com\/nl\/aviso-legal\/\" \/>\n<meta property=\"og:site_name\" content=\"Thuiszorg Euro Cl\u00ednica Rinc\u00f3n\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-27T09:58:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\">\n\t<meta name=\"twitter:data1\" content=\"bottlepostmedia\">\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\">\n\t<meta name=\"twitter:data2\" content=\"3 minuten\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/thuiszorgeuroclinicarincon.com\/de\/#website\",\"url\":\"https:\/\/thuiszorgeuroclinicarincon.com\/de\/\",\"name\":\"Thuiszorg Euro Cl\\u00ednica Rinc\\u00f3n\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/thuiszorgeuroclinicarincon.com\/de\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/thuiszorgeuroclinicarincon.com\/nl\/aviso-legal\/#webpage\",\"url\":\"https:\/\/thuiszorgeuroclinicarincon.com\/nl\/aviso-legal\/\",\"name\":\"Aviso legal - Thuiszorg Euro Cl\\u00ednica Rinc\\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/thuiszorgeuroclinicarincon.com\/de\/#website\"},\"datePublished\":\"2018-12-24T15:27:08+00:00\",\"dateModified\":\"2018-12-27T09:58:46+00:00\",\"inLanguage\":\"nl\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/thuiszorgeuroclinicarincon.com\/nl\/aviso-legal\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/thuiszorgeuroclinicarincon.com\/nl\/wp-json\/wp\/v2\/pages\/10286\/"}],"collection":[{"href":"https:\/\/thuiszorgeuroclinicarincon.com\/nl\/wp-json\/wp\/v2\/pages\/"}],"about":[{"href":"https:\/\/thuiszorgeuroclinicarincon.com\/nl\/wp-json\/wp\/v2\/types\/page\/"}],"author":[{"embeddable":true,"href":"https:\/\/thuiszorgeuroclinicarincon.com\/nl\/wp-json\/wp\/v2\/users\/1\/"}],"replies":[{"embeddable":true,"href":"https:\/\/thuiszorgeuroclinicarincon.com\/nl\/wp-json\/wp\/v2\/comments\/?post=10286"}],"version-history":[{"count":4,"href":"https:\/\/thuiszorgeuroclinicarincon.com\/nl\/wp-json\/wp\/v2\/pages\/10286\/revisions\/"}],"predecessor-version":[{"id":10313,"href":"https:\/\/thuiszorgeuroclinicarincon.com\/nl\/wp-json\/wp\/v2\/pages\/10286\/revisions\/10313\/"}],"wp:attachment":[{"href":"https:\/\/thuiszorgeuroclinicarincon.com\/nl\/wp-json\/wp\/v2\/media\/?parent=10286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}